{"id":2684,"date":"2017-02-10T11:45:30","date_gmt":"2017-02-10T15:45:30","guid":{"rendered":"http:\/\/www.hurlemort.com\/blog\/?p=2684"},"modified":"2017-02-10T11:45:30","modified_gmt":"2017-02-10T15:45:30","slug":"dopelord-children-of-the-haze-2017","status":"publish","type":"post","link":"https:\/\/www.hurlemort.com\/blog\/dopelord-children-of-the-haze-2017\/","title":{"rendered":"Dopelord &#8211; Children of the Haze &#8211; 2017"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.hurlemort.com\/blog\/wp-content\/uploads\/2017\/02\/dopelord.jpg\" alt=\"\" width=\"250\" height=\"250\" class=\"alignleft size-full wp-image-2685\" srcset=\"https:\/\/www.hurlemort.com\/blog\/wp-content\/uploads\/2017\/02\/dopelord.jpg 250w, https:\/\/www.hurlemort.com\/blog\/wp-content\/uploads\/2017\/02\/dopelord-150x150.jpg 150w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" \/>Dopelord \u2013 Stoner\/Doom Metal \u2013 Pologne<br \/>\nChildren of the Haze \u2013 2017<br \/>\nGreen Plague Records<br \/>\n9\/10<\/p>\n<p>Voil\u00e0 un album bien int\u00e9ressant et vaporeux \u00e0 souhaits!  Children of the Haze est le troisi\u00e8me album de la formation Polonaise Dopelord et je d\u00e9couvre cet excellent groupe avec ce nouvel album.  Plus je m&rsquo;aventure dans le monde du Stoner et Doom, plus je fais des d\u00e9couvertes grandioses et je me d\u00e9lecte des sonorit\u00e9s profondes de cette musique du Diable.<\/p>\n<p>Dopelord incorpore des \u00e9l\u00e9ments \u00e0 la Black Sabbath avec la profondeur abyssale de Electric Wizard pour nous offrir un album planant et enfum\u00e9.  On nage en plein d\u00e9lire psych\u00e9d\u00e9lique avec de longues pi\u00e8ces lentes et puissantes.  Le fuzz est \u00e0 l&rsquo;honneur et le \u00ab\u00a0delay\u00a0\u00bb est utilis\u00e9 \u00e0 tr\u00e8s bon escient donnant le ton du voyage cosmique et d&rsquo;un \u00e9ternel r\u00eave \u00e9veill\u00e9.  La production est granuleuse un brin ce qui colle parfaitement avec le genre souhait\u00e9.  Les compositions sont de tr\u00e8s haut niveau, Dopelord est tr\u00e8s habile dans le choix de ses riffs le mettant en \u00e9vidence sur une rythmique r\u00e9gl\u00e9e comme une horloge.<\/p>\n<p>Children of the Haze est un des meilleurs albums de 2017 \u00e0 ce jour que je recommande vivement \u00e0 tous les amateurs de musique ventil\u00e9e et puissante!  <\/p>\n<p><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/5rV4YXgqnVE\" frameborder=\"0\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dopelord \u2013 Stoner\/Doom Metal \u2013 Pologne Children of the Haze \u2013 2017 Green Plague Records 9\/10 Voil\u00e0 un album bien int\u00e9ressant et vaporeux \u00e0 souhaits! Children of the Haze est le troisi\u00e8me album de la formation Polonaise Dopelord et je d\u00e9couvre cet excellent groupe avec ce nouvel album. Plus je m&rsquo;aventure dans le monde du &hellip; <a href=\"https:\/\/www.hurlemort.com\/blog\/dopelord-children-of-the-haze-2017\/\" class=\"more-link\">Continuer la lecture de <span class=\"screen-reader-text\">Dopelord &#8211; Children of the Haze &#8211; 2017<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[479],"class_list":["post-2684","post","type-post","status-publish","format-standard","hentry","category-le-gramophone","tag-dopelord-pol"],"_links":{"self":[{"href":"https:\/\/www.hurlemort.com\/blog\/wp-json\/wp\/v2\/posts\/2684","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hurlemort.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hurlemort.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hurlemort.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hurlemort.com\/blog\/wp-json\/wp\/v2\/comments?post=2684"}],"version-history":[{"count":2,"href":"https:\/\/www.hurlemort.com\/blog\/wp-json\/wp\/v2\/posts\/2684\/revisions"}],"predecessor-version":[{"id":2687,"href":"https:\/\/www.hurlemort.com\/blog\/wp-json\/wp\/v2\/posts\/2684\/revisions\/2687"}],"wp:attachment":[{"href":"https:\/\/www.hurlemort.com\/blog\/wp-json\/wp\/v2\/media?parent=2684"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hurlemort.com\/blog\/wp-json\/wp\/v2\/categories?post=2684"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hurlemort.com\/blog\/wp-json\/wp\/v2\/tags?post=2684"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}