{"id":2938,"date":"2017-05-18T10:16:14","date_gmt":"2017-05-18T14:16:14","guid":{"rendered":"http:\/\/www.hurlemort.com\/blog\/?p=2938"},"modified":"2017-05-18T10:16:14","modified_gmt":"2017-05-18T14:16:14","slug":"azarath-in-extremis-2017","status":"publish","type":"post","link":"https:\/\/www.hurlemort.com\/blog\/azarath-in-extremis-2017\/","title":{"rendered":"Azarath &#8211; In Extremis &#8211; 2017"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.hurlemort.com\/blog\/wp-content\/uploads\/2017\/05\/azarath.jpg\" alt=\"\" width=\"250\" height=\"250\" class=\"alignleft size-full wp-image-2939\" srcset=\"https:\/\/www.hurlemort.com\/blog\/wp-content\/uploads\/2017\/05\/azarath.jpg 250w, https:\/\/www.hurlemort.com\/blog\/wp-content\/uploads\/2017\/05\/azarath-150x150.jpg 150w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" \/>Azarath \u2013 Death\/Black Metal \u2013 Pologne<br \/>\nIn Extremis \u2013 2017<br \/>\nAgonia Records<br \/>\n8.5\/10<\/p>\n<p>Il arrive plus souvent qu&rsquo;autrement qu&rsquo;un ou plusieurs groupes passent sous mon radar.  Pas \u00e9vident de pouvoir r\u00e9ussir \u00e0 tout couvrir avec le nombre de groupes s\u00e9vissant dans la vaste sph\u00e8re M\u00e9tallique.  Qui plus est, mon d\u00e9clic avec le Death Metal plus extr\u00eame s&rsquo;\u00e9tant fait sur le tard vers 2009, j&rsquo;en ai forc\u00e9ment manqu\u00e9 de grands bouts.<\/p>\n<p>Toujours est-il que je d\u00e9couvre tout juste la formation Polonaise Azarath dans laquelle on retrouve Inferno de Behemoth \u00e0 la batterie.  \u00c9videment, suite \u00e0 l&rsquo;\u00e9coute du sixi\u00e8me album du groupe, les comparaisons avec Behemoth sont plus qu&rsquo;\u00e9videntes.  Azarath \u0153uvre dans le m\u00eame cr\u00e9neau en ajoutant son grain de sel et des similitudes issues d&rsquo;autres formations Polonaises telles Vader et Hate.  Le niveau de composition et d&rsquo;ex\u00e9cution est tr\u00e8s \u00e9lev\u00e9, on en demande pas moins de la part d&rsquo;un groupe de cette trempe.  Les riffs sont solides et relativement assez complexes et les arrangements sont tout de m\u00eame assez efficaces.  Azarath joue la carte du ultra rapide et la d\u00e9fonce totale mais tous les instruments sont \u00e0 leur place et le tout demeure audible sans tomber dans le pi\u00e8ge de la cacophonie.<\/p>\n<p>In Extremis est un excellent album de Death Metal noirci au charbon br\u00fblant et contient tout ce dont nous avons besoin pour notre dose de d\u00e9capant quotidien.  A \u00e9couter sans r\u00e9serves avec un haut taux de d\u00e9cibels.<\/p>\n<p><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/PkOqzLUXPAU\" frameborder=\"0\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Azarath \u2013 Death\/Black Metal \u2013 Pologne In Extremis \u2013 2017 Agonia Records 8.5\/10 Il arrive plus souvent qu&rsquo;autrement qu&rsquo;un ou plusieurs groupes passent sous mon radar. Pas \u00e9vident de pouvoir r\u00e9ussir \u00e0 tout couvrir avec le nombre de groupes s\u00e9vissant dans la vaste sph\u00e8re M\u00e9tallique. Qui plus est, mon d\u00e9clic avec le Death Metal plus &hellip; <a href=\"https:\/\/www.hurlemort.com\/blog\/azarath-in-extremis-2017\/\" class=\"more-link\">Continuer la lecture de <span class=\"screen-reader-text\">Azarath &#8211; In Extremis &#8211; 2017<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[528],"class_list":["post-2938","post","type-post","status-publish","format-standard","hentry","category-le-gramophone","tag-azarath-pol"],"_links":{"self":[{"href":"https:\/\/www.hurlemort.com\/blog\/wp-json\/wp\/v2\/posts\/2938","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hurlemort.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hurlemort.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hurlemort.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hurlemort.com\/blog\/wp-json\/wp\/v2\/comments?post=2938"}],"version-history":[{"count":2,"href":"https:\/\/www.hurlemort.com\/blog\/wp-json\/wp\/v2\/posts\/2938\/revisions"}],"predecessor-version":[{"id":2941,"href":"https:\/\/www.hurlemort.com\/blog\/wp-json\/wp\/v2\/posts\/2938\/revisions\/2941"}],"wp:attachment":[{"href":"https:\/\/www.hurlemort.com\/blog\/wp-json\/wp\/v2\/media?parent=2938"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hurlemort.com\/blog\/wp-json\/wp\/v2\/categories?post=2938"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hurlemort.com\/blog\/wp-json\/wp\/v2\/tags?post=2938"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}